{"id":2539,"date":"2025-02-14T13:34:18","date_gmt":"2025-02-14T13:34:18","guid":{"rendered":"https:\/\/bettinaroessler.com\/?p=2539"},"modified":"2025-02-14T15:04:22","modified_gmt":"2025-02-14T15:04:22","slug":"easy-to-work-with-teil-2-vorbereitung","status":"publish","type":"post","link":"https:\/\/bettinaroessler.com\/index.php\/2025\/02\/14\/easy-to-work-with-teil-2-vorbereitung\/","title":{"rendered":"Easy to work with &#8211; Teil 2: Vorbereitung"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2539\" class=\"elementor elementor-2539\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bfc4acf e-flex e-con-boxed e-con e-parent\" data-id=\"bfc4acf\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ddb5f83 e-con-full e-flex e-con e-child\" data-id=\"ddb5f83\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-deb325c elementor-widget elementor-widget-text-editor\" data-id=\"deb325c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-weight: 400;\"><strong>Vorbereitung<\/strong><\/h2><p style=\"font-weight: 400;\">Gute Vorbereitung ist ein weiterer Schl\u00fcssel dazu, dass Menschen gerne mit uns arbeiten. Denn wer kennt es nicht? Ein Job w\u00fcrde leicht von der Hand gehen, h\u00e4tten alle im Vorfeld ihren Teil beigetragen. Stattdessen ver(sch)wendet man im Team viel Zeit und Energie, um \u00fcberhaupt alle Beteiligten auf den gleichen Stand zu bringen.<\/p><p style=\"font-weight: 400;\">Ob auf der Theaterb\u00fchne oder bei einem Dreh \u2013 Vorbereitung entscheidet \u00fcber den Erfolg. Sie reduziert mentale Belastung, schafft Raum f\u00fcr k\u00fcnstlerische Freiheit und beeinflusst ma\u00dfgeblich, wie professionell Darstellende wahrgenommen werden. Doch welche Faktoren genau sind essentiell f\u00fcr eine gute Vorbereitung?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a416367 e-con-full e-flex e-con e-child\" data-id=\"a416367\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b14608c eael-infobox-content-align--center eael-infobox-icon-bg-shape-none eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"b14608c\" data-element_type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <i aria-hidden=\"true\" class=\"fas fa-water\"><\/i>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h3 class=\"title\">Der Flow<\/h3>            <\/div>\n            <div><p><em>Flow<\/em>\u00a0ist einen Zustand v\u00f6lliger Vertiefung, in dem Arbeit leicht von der Hand geht.<\/p><p>Gerade auf der B\u00fchne ist der Flow nicht nur eine individuelle Erfahrung, sondern auch ein gemeinschaftliches Ph\u00e4nomen.<\/p><\/div>        <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e594a29 e-flex e-con-boxed e-con e-parent\" data-id=\"e594a29\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d1f858 elementor-widget elementor-widget-text-editor\" data-id=\"4d1f858\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"font-weight: 400;\"><strong>Warum Vorbereitung \u00fcber Professionalit\u00e4t entscheidet<\/strong><\/h2><h4 style=\"font-weight: 400;\"><span style=\"color: #ba5a87;\"><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/15.0.3\/svg\/2714.svg\" alt=\"\u2714\" \/><strong>Verl\u00e4sslichkeit in Produktionen<\/strong><\/span><\/h4><p style=\"font-weight: 400;\">Gute individuelle Vorbereitung gibt dem gesamten Team Sicherheit, spart Zeit und erm\u00f6glicht eine tiefere Auseinandersetzung mit dem St\u00fcck. <br \/>Was selbstverst\u00e4ndlich erscheint, stellt sich oft als Hindernis dar. Daher sollten Texte ehest baldig gelernt werden, Choreographien wiederholt, Auf- und Abg\u00e4nge (auch \u00c4nderungen) notiert werden. Je mehr Grundger\u00fcst bei allen Beteiligten bereits vorhanden ist, umso intensiver und tiefgehender kann gearbeitet werden. Texte, Choreographien oder Lieder m\u00fcssen also weitgehend selbstst\u00e4ndig zu eigen gemacht werden.<\/p><p style=\"font-weight: 400;\"><span style=\"color: #ba5a87;\"><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/15.0.3\/svg\/2714.svg\" alt=\"\u2714\" \/><strong>K\u00fcnstlerische Tiefe und Routine<\/strong><\/span><\/p><p style=\"font-weight: 400;\">Wenn Grundstrukturen verinnerlicht sind, bleibt Raum f\u00fcr Ausdruck und Improvisation.<\/p><p style=\"font-weight: 400;\">Jede Performance stellt hohe Anforderungen an unser Gehirn: Text lernen, Handlung verstehen, Schl\u00fcsselmomente kennen, Emotionen abrufen, auf Szenenpartner:innen reagieren \u2013 all das erfordert h\u00f6chste Konzentration. <br \/>Psychologische Studien zeigen jedoch, dass unser Gehirn nur eine begrenzte Kapazit\u00e4t f\u00fcr Aufmerksamkeit hat:<br \/>Ein hilfreiches Bild ist der\u00a0<em>Scheinwerferkegel auf einer dunklen B\u00fchne<\/em>: Was im Lichtkegel liegt, nehmen wir wahr, was au\u00dferhalb liegt, bleibt uns verborgen und ist unm\u00f6glich zu greifen. Durch gezielte Vorbereitung richten wir den Scheinwerferkegel auf weitere wesentliche Dinge. Wir verschwenden unsere wertvollen Kapazit\u00e4ten nicht auf pers\u00f6nliche Unsicherheiten und daher notwendige Improvisation, sondern richten sie auf die k\u00fcnstlerische Arbeit.<\/p><p style=\"font-weight: 400;\">Gut vorbereitete Darsteller:innen haben Texte, Bewegungen, Abfolgen und Absprachen verinnerlicht, dass mehr Raum f\u00fcr das bleibt, was wirklich z\u00e4hlt: die Verk\u00f6rperung und die emotionale Tiefe der Performance.<\/p><p style=\"font-weight: 400;\"><span style=\"color: #ba5a87;\"><img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/15.0.3\/svg\/2714.svg\" alt=\"\u2714\" \/><strong>Der Flow<\/strong><\/span><\/p><p style=\"font-weight: 400;\">Auch hier gilt: Wer das Skript und Rolle verinnerlicht hat, kann ins Spielen kommen. Der Psychologe Mih\u00e1ly Cs\u00edkszentmih\u00e1lyi beschreibt den\u00a0<em>Flow<\/em>\u00a0als einen Zustand v\u00f6lliger Vertiefung, in dem Arbeit leicht von der Hand geht. Eine gr\u00fcndliche Vorbereitung beg\u00fcnstigt diesen Zustand:<\/p><ul style=\"font-weight: 400;\"><li>Je ausf\u00fchrlicher die Basis einstudiert wurde (Text, Bewegung, St\u00fcckinterpretation, und dgl.), desto besser k\u00f6nnen sich die Darstellenden voll auf die Szene konzentrieren.<\/li><li>Durch die Sicherheit, die man dadurch bekommt, tritt der innere Kritiker bzw. die innere Kritikerin in den Hintergrund \u2013 die Performance wird intuitiv.<\/li><li>Das Publikum sp\u00fcrt diese nat\u00fcrliche Pr\u00e4senz und wird st\u00e4rker ins Geschehen gezogen.<\/li><\/ul><p style=\"font-weight: 400;\">Flow entsteht, wenn eine Aufgabe herausfordernd, aber nicht \u00fcberfordernd ist. Vorbereitung sorgt daf\u00fcr, dass die Balance zwischen Kontrolle und Spontanit\u00e4t stimmt.<\/p><p style=\"font-weight: 400;\">Gerade auf der B\u00fchne ist der <em>Flow<\/em> nicht nur eine individuelle Erfahrung, sondern auch ein gemeinschaftliches Ph\u00e4nomen. Wenn alle Mitwirkenden sich aufeinander einlassen und auf Impulse aus der Szene reagieren, entsteht eine lebendige, organische Dynamik. Dialoge wirken nat\u00fcrlicher, Timing und Rhythmus finden sich fast automatisch, und die Verbindung zwischen den Spielenden wird sp\u00fcrbar. Diese Art von harmonischem Zusammenspiel tr\u00e4gt dazu bei, dass die Szenen authentisch und mitrei\u00dfend wirken \u2013 sowohl f\u00fcr die Darstellenden selbst als auch f\u00fcr das Publikum.<\/p><h2><strong>Vorbereitung als Schl\u00fcssel zur k\u00fcnstlerischen Freiheit<\/strong><\/h2><p style=\"font-weight: 400;\">Auf der B\u00fchne geht es darum, pr\u00e4sent zu sein, Emotionen sp\u00fcrbar zu machen und das Publikum in eine andere Welt zu entf\u00fchren. Doch wahre Spontanit\u00e4t entsteht nicht aus dem Nichts \u2013 sie ist das Ergebnis solider Vorbereitung. Je sicherer der Text, die Abl\u00e4ufe und das Verst\u00e4ndnis der Rolle, desto freier kann gespielt werden.<\/p><p style=\"font-weight: 400;\">Die besten Darsteller:innen sind die, die sich nicht allein auf ihr Talent verlassen. Talent, Disziplin und Vorbereitung sind eins. \u00a0<\/p><p style=\"font-weight: 400;\">Welche Erfahrungen hast du in den Vorbereitungsprozessen gemacht? Teilst du diese Einsch\u00e4tzungen?<\/p><p style=\"font-weight: 400;\">Im n\u00e4chsten Blogbeitrag geht es mit der Reihe \u201eEasy to work with\u201c weiter.<\/p><p style=\"font-weight: 400;\">Bis dahin w\u00fcnsche ich dir alles Liebe,<\/p><p>Bettina<\/p><h2 style=\"font-weight: 400;\">\u00a0<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vorbereitung Gute Vorbereitung ist ein weiterer Schl\u00fcssel dazu, dass Menschen gerne mit uns arbeiten. Denn wer kennt es nicht? Ein Job w\u00fcrde leicht von der Hand gehen, h\u00e4tten alle im Vorfeld ihren Teil beigetragen. Stattdessen ver(sch)wendet man im Team viel Zeit und Energie, um \u00fcberhaupt alle Beteiligten auf den gleichen Stand zu bringen. Ob auf &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/bettinaroessler.com\/index.php\/2025\/02\/14\/easy-to-work-with-teil-2-vorbereitung\/\" class=\"more-link\">Read more<span class=\"screen-reader-text\"> &#8222;Easy to work with &#8211; Teil 2: Vorbereitung&#8220;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,35,59,55],"tags":[],"class_list":["post-2539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-art-life-balance","category-beruf-karriere","category-easy-to-work-with","category-motivation-disziplin"],"_links":{"self":[{"href":"https:\/\/bettinaroessler.com\/index.php\/wp-json\/wp\/v2\/posts\/2539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bettinaroessler.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bettinaroessler.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bettinaroessler.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bettinaroessler.com\/index.php\/wp-json\/wp\/v2\/comments?post=2539"}],"version-history":[{"count":13,"href":"https:\/\/bettinaroessler.com\/index.php\/wp-json\/wp\/v2\/posts\/2539\/revisions"}],"predecessor-version":[{"id":2553,"href":"https:\/\/bettinaroessler.com\/index.php\/wp-json\/wp\/v2\/posts\/2539\/revisions\/2553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bettinaroessler.com\/index.php\/wp-json\/wp\/v2\/media\/2544"}],"wp:attachment":[{"href":"https:\/\/bettinaroessler.com\/index.php\/wp-json\/wp\/v2\/media?parent=2539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bettinaroessler.com\/index.php\/wp-json\/wp\/v2\/categories?post=2539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bettinaroessler.com\/index.php\/wp-json\/wp\/v2\/tags?post=2539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}